﻿{"id":421,"count":2,"description":"","link":"https:\/\/www.hefe-und-mehr.de\/en\/tag\/salt\/","name":"Salt","slug":"salt","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.hefe-und-mehr.de\/en\/wp-json\/wp\/v2\/tags\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hefe-und-mehr.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.hefe-und-mehr.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.hefe-und-mehr.de\/en\/wp-json\/wp\/v2\/posts?tags=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}